{"id":2630,"date":"2024-09-18T09:32:08","date_gmt":"2024-09-18T07:32:08","guid":{"rendered":"https:\/\/soluwater.com\/?page_id=2630"},"modified":"2024-09-18T10:00:23","modified_gmt":"2024-09-18T08:00:23","slug":"confidentialite","status":"publish","type":"page","link":"https:\/\/soluwater.com\/fr\/privacidad\/","title":{"rendered":"Vie priv\u00e9e"},"content":{"rendered":"<div id=\"fws_6a572e4e4e656\"  data-column-margin=\"default\" data-midnight=\"light\" data-top-percent=\"10%\" data-bottom-percent=\"7%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: calc(100vw * 0.07); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\"  style=\"background-image: url(https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/bg-chatbot-v1.svg); background-position: left top; background-repeat: no-repeat; background-color: #141414; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background-color:#0a0a0a;  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col centered-text no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a572e4e4f26d\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1726644720339\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h2>Petites lettres, impact g\u00e9ant :<br \/>\nD\u00e9couvrez notre <strong>politique de confidentialit\u00e9<\/strong>.<br \/>\nChez Soluwater, nous sommes transparents.<\/h2>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t\t<\/div>\n<\/div>\n\n\n\n\n<p>&nbsp;<\/p>\n<p><strong>soluwater.com<\/strong><\/p>\n<p><strong>1. <\/strong><strong>POLITIQUE DE CONFIDENTIALIT\u00c9 ET DE PROTECTION DES DONN\u00c9ES<\/strong><\/p>\n<p>Conform\u00e9ment \u00e0 la l\u00e9gislation en vigueur, Soluwater (ci-apr\u00e8s \u00e9galement d\u00e9nomm\u00e9 le Site Web) s'engage \u00e0 adopter les mesures techniques et organisationnelles n\u00e9cessaires, selon le niveau de s\u00e9curit\u00e9 appropri\u00e9 au risque des donn\u00e9es collect\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lois auxquelles cette politique de confidentialit\u00e9 se conforme<\/strong><\/p>\n<p>Cette politique de confidentialit\u00e9 est adapt\u00e9e \u00e0 la r\u00e9glementation espagnole et europ\u00e9enne en vigueur en mati\u00e8re de protection des donn\u00e9es personnelles sur Internet. Plus pr\u00e9cis\u00e9ment, elle respecte les r\u00e8gles suivantes :<\/p>\n<ul>\n<li>Le R\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil, du 27 avril 2016, relatif \u00e0 la protection des personnes physiques \u00e0 l'\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es (RGPD).<\/li>\n<li>La Loi Organique 3\/2018, du 5 d\u00e9cembre, relative \u00e0 la protection des donn\u00e9es personnelles et \u00e0 la garantie des droits num\u00e9riques (LOPD-GDD).<\/li>\n<li>Le d\u00e9cret royal 1720\/2007, du 21 d\u00e9cembre, approuvant le r\u00e8glement d'application de la loi organique 15\/1999, du 13 d\u00e9cembre, sur la protection des donn\u00e9es \u00e0 caract\u00e8re personnel (RDLOPD).<\/li>\n<li>La loi 34\/2002, du 11 juillet, relative aux services de la soci\u00e9t\u00e9 de l'information et au commerce \u00e9lectronique (LSSI-CE).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Identit\u00e9 du responsable du traitement des donn\u00e9es personnelles<\/strong><\/p>\n<p>Le responsable du traitement des donn\u00e9es personnelles collect\u00e9es sur Soluwater est : Mobile Water Solutions S.L., titulaire du NIF\/CIF : ESB10945541 et inscrite au Registre du Commerce de Madrid sous les donn\u00e9es d'enregistrement suivantes : Volume 44.536, Feuillet 120, Page M-784575, Inscription 1\u00e8re, repr\u00e9sent\u00e9e par : Carlos Segura Roux (ci-apr\u00e8s, le Responsable du traitement). Vos coordonn\u00e9es sont les suivantes :<\/p>\n<p>&nbsp;<\/p>\n<p>Adresse : Calle Palier 58, 28914 \u2013 Legan\u00e9s, Madrid, Espagne<\/p>\n<p>Num\u00e9ro de t\u00e9l\u00e9phone de contact : +34913783300<\/p>\n<p>Adresse email de contact : rgpd@soluwater.com<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Enregistrement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/strong><\/p>\n<p>Conform\u00e9ment \u00e0 ce qui est \u00e9tabli dans le RGPD et la LOPD-GDD, nous vous informons que les donn\u00e9es personnelles collect\u00e9es par Soluwater, par le biais des formulaires pr\u00e9sents sur ses pages, seront int\u00e9gr\u00e9es et trait\u00e9es dans notre fichier afin de pouvoir faciliter, acc\u00e9l\u00e9rer et respecter les engagements \u00e9tablis entre Soluwater et l'Utilisateur ou le maintien de la relation qui s'\u00e9tablit dans les formulaires que celui-ci remplit, ou pour r\u00e9pondre \u00e0 une demande ou une consultation de sa part. De m\u00eame, conform\u00e9ment aux dispositions du RGPD et de la LOPD-GDD, sauf exception pr\u00e9vue \u00e0 l'article 30.5 du RGPD, un registre des activit\u00e9s de traitement est tenu, pr\u00e9cisant, selon ses finalit\u00e9s, les activit\u00e9s de traitement effectu\u00e9es et les autres circonstances \u00e9tablies par le RGPD.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Principes applicables au traitement des donn\u00e9es personnelles<\/strong><\/p>\n<p>Le traitement des donn\u00e9es personnelles de l'Utilisateur sera soumis aux principes suivants \u00e9nonc\u00e9s \u00e0 l'article 5 du RGPD et aux articles 4 et suivants de la loi organique 3\/2018, du 5 d\u00e9cembre, sur la protection des donn\u00e9es personnelles et la garantie des droits num\u00e9riques :<\/p>\n<ul>\n<li>Principe de lic\u00e9it\u00e9, loyaut\u00e9 et transparence : le consentement de l'Utilisateur sera requis \u00e0 tout moment apr\u00e8s information enti\u00e8rement transparente sur les finalit\u00e9s pour lesquelles les donn\u00e9es personnelles sont collect\u00e9es.<\/li>\n<li>Principe de limitation de la finalit\u00e9 : les donn\u00e9es \u00e0 caract\u00e8re personnel sont collect\u00e9es pour des finalit\u00e9s d\u00e9termin\u00e9es, explicites et l\u00e9gitimes.<\/li>\n<li>Principe de minimisation des donn\u00e9es : seules les donn\u00e9es \u00e0 caract\u00e8re personnel strictement n\u00e9cessaires au regard des finalit\u00e9s pour lesquelles elles sont trait\u00e9es seront collect\u00e9es.<\/li>\n<li>Principe d'exactitude : les donn\u00e9es \u00e0 caract\u00e8re personnel doivent \u00eatre exactes et tenues \u00e0 jour.<\/li>\n<li>Principe de limitation de la dur\u00e9e de conservation : les donn\u00e9es personnelles ne seront conserv\u00e9es sous une forme permettant l'identification des utilisateurs que pendant la dur\u00e9e n\u00e9cessaire aux finalit\u00e9s pour lesquelles elles sont trait\u00e9es.<\/li>\n<li>Principe d'int\u00e9grit\u00e9 et de confidentialit\u00e9 : les donn\u00e9es personnelles seront trait\u00e9es de mani\u00e8re \u00e0 en garantir la s\u00e9curit\u00e9 et la confidentialit\u00e9.<\/li>\n<li>Principe de responsabilit\u00e9 proactive : le responsable du traitement est responsable de s'assurer que les principes ci-dessus sont respect\u00e9s.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Cat\u00e9gories de donn\u00e9es personnelles<\/strong><\/p>\n<p>Les cat\u00e9gories de donn\u00e9es trait\u00e9es chez Soluwater sont uniquement des donn\u00e9es d'identification. En aucun cas, il n'est trait\u00e9 de cat\u00e9gories particuli\u00e8res de donn\u00e9es personnelles au sens de l'article 9 du RGPD.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Base juridique du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/strong><\/p>\n<p>La base l\u00e9gale du traitement des donn\u00e9es personnelles est le consentement. Soluwater s'engage \u00e0 recueillir le consentement expr\u00e8s et v\u00e9rifiable de l'Utilisateur pour le traitement de ses donn\u00e9es personnelles \u00e0 une ou plusieurs fins sp\u00e9cifiques.<\/p>\n<p>L&#x27;utilisateur a le droit de retirer son consentement \u00e0 tout moment. Retirer son consentement est aussi simple que de le donner. En r\u00e8gle g\u00e9n\u00e9rale, le retrait du consentement n&#x27;affectera pas l&#x27;utilisation du site web.<\/p>\n<p>Dans les occasions o\u00f9 l'Utilisateur doit ou peut fournir ses donn\u00e9es par le biais de formulaires pour effectuer des consultations, demander des informations ou pour des raisons li\u00e9es au contenu du Site Web, il sera inform\u00e9 si la saisie de l'un d'entre eux est obligatoire parce qu'ils sont indispensables au bon d\u00e9roulement de l'op\u00e9ration effectu\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Finalit\u00e9s du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel<\/strong><\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel sont collect\u00e9es et trait\u00e9es par Soluwater dans le but de faciliter, d&#x27;acc\u00e9l\u00e9rer et de respecter les engagements pris entre le site web et l&#x27;utilisateur, ou d&#x27;assurer le suivi de la relation \u00e9tablie \u00e0 partir des formulaires remplis par ce dernier, ou encore de r\u00e9pondre \u00e0 une demande ou \u00e0 une question.<\/p>\n<p>De m\u00eame, les donn\u00e9es pourront \u00eatre utilis\u00e9es \u00e0 des fins commerciales de personnalisation, op\u00e9rationnelles et statistiques, ainsi que pour les activit\u00e9s relevant de l&#x27;objet social de Soluwater, et pour l&#x27;extraction, le stockage de donn\u00e9es et des \u00e9tudes de marketing visant \u00e0 adapter le contenu propos\u00e9 \u00e0 l&#x27;utilisateur, ainsi qu&#x27;\u00e0 am\u00e9liorer la qualit\u00e9, le fonctionnement et la navigation sur le site web.<\/p>\n<p>Au moment de la collecte des donn\u00e9es personnelles, l'Utilisateur sera inform\u00e9 du ou des finalit\u00e9s sp\u00e9cifiques du traitement auquel les donn\u00e9es personnelles seront destin\u00e9es ; c'est-\u00e0-dire de l'utilisation ou des utilisations qui seront faites des informations recueillies.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>P\u00e9riodes de conservation des donn\u00e9es personnelles<\/strong><\/p>\n<p>Les donn\u00e9es \u00e0 caract\u00e8re personnel ne seront conserv\u00e9es que pendant la dur\u00e9e minimale n\u00e9cessaire aux fins de leur traitement et, dans tous les cas, uniquement pendant la p\u00e9riode suivante : 24 mois, ou jusqu&#x27;\u00e0 ce que l&#x27;utilisateur en demande la suppression.<\/p>\n<p>Au moment de la collecte des donn\u00e9es \u00e0 caract\u00e8re personnel, l&#x27;Utilisateur sera inform\u00e9 de la dur\u00e9e de conservation de ces donn\u00e9es ou, lorsque cela n&#x27;est pas possible, des crit\u00e8res utilis\u00e9s pour d\u00e9terminer cette dur\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Destinataires des donn\u00e9es personnelles<\/strong><\/p>\n<p>Les donn\u00e9es personnelles de l'Utilisateur seront partag\u00e9es avec les destinataires ou cat\u00e9gories de destinataires suivants :<\/p>\n<ul>\n<li>IONOS Cloud S.L.U., Avenida de la Vega, 1, immeuble Veganova, 3e \u00e9tage, porte C, Alcobendas 28108, Madrid.<\/li>\n<li>MailerLite Limited, sise au rez-de-chauss\u00e9e, 71 Lower Baggot Street, Dublin 2, D02 P593, Irlande.<\/li>\n<li>MailerCheck Inc., dont le si\u00e8ge social est situ\u00e9 au 228 Park Ave S, PMB 54955, New York, New York 10003-1502, \u00c9tats-Unis.<\/li>\n<li>Google Ireland Limited, dont le si\u00e8ge social est situ\u00e9 \u00e0 Gordon House, Barrow Street, Dublin 4, Irlande.<\/li>\n<li>LinkedIn Ireland Unlimited Company, soci\u00e9t\u00e9 enregistr\u00e9e \u00e0 Wilton Place, Dublin 2, Irlande.<\/li>\n<\/ul>\n<p>Si le responsable du traitement a l&#x27;intention de transf\u00e9rer des donn\u00e9es \u00e0 caract\u00e8re personnel vers un pays tiers ou une organisation internationale, il informera l&#x27;utilisateur, au moment de la collecte des donn\u00e9es \u00e0 caract\u00e8re personnel, du pays tiers ou de l&#x27;organisation internationale vers lequel il est pr\u00e9vu de transf\u00e9rer les donn\u00e9es, ainsi que de l&#x27;existence ou de l&#x27;absence d&#x27;une d\u00e9cision d&#x27;ad\u00e9quation de la Commission.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Donn\u00e9es personnelles des mineurs<\/strong><\/p>\n<p>Conform\u00e9ment aux dispositions de l'article 8 du RGPD et de l'article 7 de la loi organique 3\/2018, du 5 d\u00e9cembre, sur la protection des donn\u00e9es personnelles et la garantie des droits num\u00e9riques, seuls les personnes de plus de 14 ans peuvent donner leur consentement pour le traitement de leurs donn\u00e9es personnelles de mani\u00e8re licite par Soluwater. S'il s'agit d'un mineur de moins de 14 ans, le consentement des parents ou tuteurs sera n\u00e9cessaire pour le traitement, et celui-ci ne sera consid\u00e9r\u00e9 comme licite que dans la mesure o\u00f9 ces derniers l'auront autoris\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Secret et s\u00e9curit\u00e9 des donn\u00e9es personnelles<\/strong><\/p>\n<p>Soluwater s'engage \u00e0 prendre les mesures techniques et organisationnelles n\u00e9cessaires, en fonction du niveau de s\u00e9curit\u00e9 adapt\u00e9 au risque des donn\u00e9es collect\u00e9es, afin de garantir la s\u00e9curit\u00e9 des donn\u00e9es personnelles et d'\u00e9viter la destruction, la perte ou l'alt\u00e9ration accidentelle ou illicite de donn\u00e9es personnelles transmises, conserv\u00e9es ou trait\u00e9es d'une autre mani\u00e8re, ou la communication ou l'acc\u00e8s non autoris\u00e9 \u00e0 ces donn\u00e9es.<\/p>\n<p>Le site Web est dot\u00e9 d'un certificat SSL (Secure Socket Layer), qui garantit que les donn\u00e9es personnelles sont transmises de mani\u00e8re s\u00e9curis\u00e9e et confidentielle, la transmission des donn\u00e9es entre le serveur et l'utilisateur, ainsi qu'en retour, \u00e9tant enti\u00e8rement chiffr\u00e9e ou crypt\u00e9e.<\/p>\n<p>Cependant, du fait que Soluwater ne peut garantir l'impr\u00e9gnabilit\u00e9 d'Internet ni l'absence totale de hackers ou d'autres personnes acc\u00e9dant de mani\u00e8re frauduleuse aux donn\u00e9es personnelles, le responsable du traitement s'engage \u00e0 informer l'Utilisateur dans les meilleurs d\u00e9lais en cas de violation de la s\u00e9curit\u00e9 des donn\u00e9es personnelles susceptible d'engendrer un risque \u00e9lev\u00e9 pour les droits et libert\u00e9s des personnes physiques. Conform\u00e9ment \u00e0 l'article 4 du RGPD, une violation de la s\u00e9curit\u00e9 des donn\u00e9es personnelles s'entend de toute violation de la s\u00e9curit\u00e9 qui entra\u00eene la destruction, la perte, la modification accidentelle ou illicite de donn\u00e9es \u00e0 caract\u00e8re personnel transmises, conserv\u00e9es ou trait\u00e9es d'une autre mani\u00e8re, ou la communication ou l'acc\u00e8s non autoris\u00e9 \u00e0 de telles donn\u00e9es.<\/p>\n<p>Les donn\u00e9es personnelles seront trait\u00e9es de mani\u00e8re confidentielle par le Responsable du traitement, qui s'engage \u00e0 informer et \u00e0 garantir, par une obligation l\u00e9gale ou contractuelle, que cette confidentialit\u00e9 soit respect\u00e9e par ses employ\u00e9s, associ\u00e9s et toute personne \u00e0 qui il rendra les informations accessibles.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Droits issus du traitement des donn\u00e9es personnelles<\/strong><\/p>\n<p>L'Utilisateur a sur Soluwater et pourra, par cons\u00e9quent, exercer face au Responsable du traitement les droits suivants reconnus dans le RGPD et la Loi Organique 3\/2018, du 5 d\u00e9cembre, de Protection des Donn\u00e9es Personnelles et garantie des droits num\u00e9riques :<\/p>\n<ul>\n<li><em>Droit d'acc\u00e8s<\/em>\u00a0Il s'agit du droit de l'Utilisateur d'obtenir la confirmation que Soluwater traite ou non ses donn\u00e9es personnelles et, si c'est le cas, d'obtenir des informations sur ses donn\u00e9es personnelles concr\u00e8tes et sur le traitement que Soluwater a effectu\u00e9 ou effectue, ainsi que, entre autres, des informations disponibles sur l'origine de ces donn\u00e9es et les destinataires des communications effectu\u00e9es ou pr\u00e9vues.<\/li>\n<li><em>Droit de rectification\u00a0:<\/em>\u00a0Le droit de l'Utilisateur de faire rectifier ses donn\u00e9es personnelles qui s'av\u00e9reraient inexactes ou, compte tenu des finalit\u00e9s du traitement, incompl\u00e8tes.<\/li>\n<li><em>Droit de suppression (\u00ab le droit \u00e0 l'oubli \u00bb) :<\/em>\u00a0Le droit de l'Utilisateur, sous r\u00e9serve des dispositions l\u00e9gislatives en vigueur qui disposeraient le contraire, d'obtenir la suppression de ses donn\u00e9es personnelles lorsqu'elles ne sont plus n\u00e9cessaires aux fins pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es ou trait\u00e9es ; l'Utilisateur a retir\u00e9 son consentement au traitement et celui-ci ne repose sur aucune autre base l\u00e9gale ; l'Utilisateur s'oppose au traitement et il n'existe aucun autre motif l\u00e9gitime pour poursuivre le m\u00eame ; les donn\u00e9es personnelles ont \u00e9t\u00e9 trait\u00e9es ill\u00e9galement ; les donn\u00e9es personnelles doivent \u00eatre supprim\u00e9es conform\u00e9ment \u00e0 une obligation l\u00e9gale ; ou les donn\u00e9es personnelles ont \u00e9t\u00e9 obtenues dans le cadre d'une offre directe de services de la soci\u00e9t\u00e9 de l'information \u00e0 un mineur de 14 ans. Outre la suppression des donn\u00e9es, le responsable du traitement, compte tenu de la technologie disponible et du co\u00fbt de sa mise en \u0153uvre, devra prendre des mesures raisonnables pour informer les responsables qui traitent les donn\u00e9es personnelles de la demande de la personne concern\u00e9e de supprimer tout lien vers ces donn\u00e9es personnelles.<\/li>\n<li><em>Droit \u00e0 la limitation du traitement :<\/em>\u00a0C'est le droit de l'Utilisateur de limiter le traitement de ses donn\u00e9es personnelles. L'Utilisateur a le droit d'obtenir la limitation du traitement lorsque l'exactitude de ses donn\u00e9es personnelles est contest\u00e9e\u00a0; le traitement est illicite\u00a0; le responsable du traitement n'a plus besoin des donn\u00e9es personnelles, mais l'Utilisateur en a besoin pour l'exercice de revendications\u00a0; et lorsque l'Utilisateur s'est oppos\u00e9 au traitement.<\/li>\n<li><em>Droit \u00e0 la portabilit\u00e9 des donn\u00e9es :<\/em>\u00a0Dans le cas o\u00f9 le traitement est effectu\u00e9 par des moyens automatis\u00e9s, l'Utilisateur a le droit de recevoir de la part du responsable du traitement ses donn\u00e9es personnelles dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, et de les transmettre \u00e0 un autre responsable du traitement. Dans la mesure o\u00f9 cela est techniquement possible, le responsable du traitement transmettra directement les donn\u00e9es \u00e0 cet autre responsable.<\/li>\n<li><em>Droit d'opposition :<\/em>\u00a0Il s'agit du droit de l'Utilisateur de refuser le traitement de ses donn\u00e9es personnelles ou d'en exiger l'arr\u00eat du traitement par Soluwater.<\/li>\n<li><em>Droit de ne pas faire l'objet d'une d\u00e9cision fond\u00e9e uniquement sur un traitement automatis\u00e9, y compris un profilage :<\/em>\u00a0Il s'agit du droit de l'utilisateur de ne pas faire l'objet d'une d\u00e9cision fond\u00e9e uniquement sur un traitement automatis\u00e9, y compris le profilage, qui produit des effets juridiques le concernant ou qui l'affecte de mani\u00e8re significative, sauf si la l\u00e9gislation en vigueur en dispose autrement.<\/li>\n<\/ul>\n<p>Par cons\u00e9quent, l'Utilisateur pourra exercer ses droits au moyen d'une communication \u00e9crite adress\u00e9e au responsable du traitement avec la r\u00e9f\u00e9rence \u00ab RGPD-https:\/\/soluwater.com \u00bb, en pr\u00e9cisant :<\/p>\n<ul>\n<li>Nom, pr\u00e9noms de l'utilisateur et copie de la carte d'identit\u00e9. Dans les cas o\u00f9 la repr\u00e9sentation est admise, l'identification de la personne repr\u00e9sentant l'utilisateur par le m\u00eame moyen sera \u00e9galement n\u00e9cessaire, ainsi que le document prouvant la repr\u00e9sentation. La photocopie de la carte d'identit\u00e9 pourra \u00eatre remplac\u00e9e par tout autre moyen l\u00e9galement valable qui justifie l'identit\u00e9.<\/li>\n<li>Demande motiv\u00e9e pr\u00e9cisant les raisons sp\u00e9cifiques de la requ\u00eate ou les informations auxquelles l'on souhaite acc\u00e9der.<\/li>\n<li>Domicile pour les besoins de notifications.<\/li>\n<li>Date et signature du demandeur.<\/li>\n<li>Tout document justifiant la requ\u00eate qu'il formule.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Cette demande et tout autre document ci-joint peuvent \u00eatre envoy\u00e9s \u00e0 l'adresse et\/ou \u00e0 l'adresse e-mail suivantes :<\/p>\n<p>Adresse postale : Calle Palier 58, 28914 \u2013 Legan\u00e9s, Madrid, Espagne<\/p>\n<p>Courriel :\u00a0<a href=\"mailto:rgpd@soluwater.com\">rgpd@soluwater.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Liens vers des sites web de tiers<\/strong><\/p>\n<p>Le Site Web peut inclure des hyperliens ou des liens permettant d'acc\u00e9der \u00e0 des pages web de tiers autres que Soluwater, et qui ne sont donc pas exploit\u00e9s par Soluwater. Les titulaires de tels sites web disposeront de leurs propres politiques de protection des donn\u00e9es, \u00e9tant eux-m\u00eames, dans chaque cas, responsables de leurs propres fichiers et de leurs propres pratiques de confidentialit\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>R\u00e9clamations aupr\u00e8s de l'autorit\u00e9 de contr\u00f4le<\/strong><\/p>\n<p>En cas de probl\u00e8me ou de violation de la r\u00e9glementation en vigueur dans la mani\u00e8re dont vos donn\u00e9es personnelles sont trait\u00e9es, vous avez le droit d'exercer un recours judiciaire effectif et de d\u00e9poser une plainte aupr\u00e8s d'une autorit\u00e9 de contr\u00f4le, notamment dans l'\u00c9tat o\u00f9 vous r\u00e9sidez habituellement, travaillez ou o\u00f9 l'infraction pr\u00e9sum\u00e9e a eu lieu. Dans le cas de l'Espagne, l'autorit\u00e9 de contr\u00f4le est l'Agence espagnole de protection des donn\u00e9es (<a href=\"https:\/\/www.aepd.es\/\">https:\/\/www.aepd.es\/<\/a>).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>2. ACCEPTATION ET MODIFICATIONS DE CETTE POLITIQUE DE CONFIDENTIALIT\u00c9<\/strong><\/p>\n<p>Il est n\u00e9cessaire que l'Utilisateur ait lu et soit d'accord avec les conditions de protection des donn\u00e9es \u00e0 caract\u00e8re personnel contenues dans la pr\u00e9sente Politique de Confidentialit\u00e9, ainsi qu'il accepte le traitement de ses donn\u00e9es personnelles afin que le Responsable du traitement puisse y proc\u00e9der dans la forme, durant les d\u00e9lais et pour les finalit\u00e9s indiqu\u00e9es. L'utilisation du Site Web impliquera l'acceptation de la Politique de Confidentialit\u00e9 dudit Site.<\/p>\n<p>Soluwater se r\u00e9serve le droit de modifier sa Politique de Confidentialit\u00e9, \u00e0 sa seule discr\u00e9tion, ou en raison d'un changement l\u00e9gislatif, jurisprudentiel ou doctrinal de l'Agence Espagnole de Protection des Donn\u00e9es. Les changements ou mises \u00e0 jour de cette Politique de Confidentialit\u00e9 ne seront pas explicitement notifi\u00e9s \u00e0 l'Utilisateur. Il est recommand\u00e9 \u00e0 l'Utilisateur de consulter cette page p\u00e9riodiquement afin de se tenir inform\u00e9 des derniers changements ou mises \u00e0 jour.<\/p>\n<p>Cette politique de confidentialit\u00e9 a \u00e9t\u00e9 mise \u00e0 jour pour se conformer au r\u00e8glement (UE) 2016\/679 du Parlement europ\u00e9en et du Conseil du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l'\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es (RGPD) et \u00e0 la loi organique 3\/2018 du 5 d\u00e9cembre sur la protection des donn\u00e9es personnelles et la garantie des droits num\u00e9riques.<\/p>\n<p>Ce document de Politique de Confidentialit\u00e9 a \u00e9t\u00e9 mis \u00e0 jour pour la derni\u00e8re fois le 05\/04\/2024.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; soluwater.com 1. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Soluwater (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas&#8230;<\/p>","protected":false},"author":2,"featured_media":1983,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-2630","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacidad - Soluwater<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soluwater.com\/fr\/confidentialite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacidad - Soluwater\" \/>\n<meta property=\"og:description\" content=\"&nbsp; soluwater.com 1. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Soluwater (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soluwater.com\/fr\/confidentialite\/\" \/>\n<meta property=\"og:site_name\" content=\"Soluwater\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T08:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/Imagen-OG-Legal.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/\",\"url\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/\",\"name\":\"Privacidad - Soluwater\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Imagen-OG-Legal.webp\",\"datePublished\":\"2024-09-18T07:32:08+00:00\",\"dateModified\":\"2024-09-18T08:00:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Imagen-OG-Legal.webp\",\"contentUrl\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Imagen-OG-Legal.webp\",\"width\":1200,\"height\":630,\"caption\":\"Conoce toda nuestra la informaci\u00f3n legal sobre Soluwater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/pt\\\/privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/soluwater.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/#website\",\"url\":\"https:\\\/\\\/soluwater.com\\\/\",\"name\":\"Soluwater\",\"description\":\"Alquiler de plantas m\u00f3viles de tratamiento de agua\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soluwater.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confidentialit\u00e9 - Soluwater","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soluwater.com\/fr\/confidentialite\/","og_locale":"fr_FR","og_type":"article","og_title":"Privacidad - Soluwater","og_description":"&nbsp; soluwater.com 1. POL\u00cdTICA DE PRIVACIDAD Y PROTECCI\u00d3N DE DATOS Respetando lo establecido en la legislaci\u00f3n vigente, Soluwater (en adelante, tambi\u00e9n Sitio Web) se compromete a adoptar las medidas t\u00e9cnicas...","og_url":"https:\/\/soluwater.com\/fr\/confidentialite\/","og_site_name":"Soluwater","article_modified_time":"2024-09-18T08:00:23+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/Imagen-OG-Legal.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"18 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soluwater.com\/pt\/privacidad\/","url":"https:\/\/soluwater.com\/pt\/privacidad\/","name":"Confidentialit\u00e9 - Soluwater","isPartOf":{"@id":"https:\/\/soluwater.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soluwater.com\/pt\/privacidad\/#primaryimage"},"image":{"@id":"https:\/\/soluwater.com\/pt\/privacidad\/#primaryimage"},"thumbnailUrl":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/Imagen-OG-Legal.webp","datePublished":"2024-09-18T07:32:08+00:00","dateModified":"2024-09-18T08:00:23+00:00","breadcrumb":{"@id":"https:\/\/soluwater.com\/pt\/privacidad\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soluwater.com\/pt\/privacidad\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/soluwater.com\/pt\/privacidad\/#primaryimage","url":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/Imagen-OG-Legal.webp","contentUrl":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/05\/Imagen-OG-Legal.webp","width":1200,"height":630,"caption":"Conoce toda nuestra la informaci\u00f3n legal sobre Soluwater"},{"@type":"BreadcrumbList","@id":"https:\/\/soluwater.com\/pt\/privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soluwater.com\/"},{"@type":"ListItem","position":2,"name":"Privacidad"}]},{"@type":"WebSite","@id":"https:\/\/soluwater.com\/#website","url":"https:\/\/soluwater.com\/","name":"Soluwater","description":"Location de stations d'\u00e9puration mobiles","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soluwater.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/pages\/2630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/comments?post=2630"}],"version-history":[{"count":7,"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/pages\/2630\/revisions"}],"predecessor-version":[{"id":2649,"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/pages\/2630\/revisions\/2649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/media\/1983"}],"wp:attachment":[{"href":"https:\/\/soluwater.com\/fr\/wp-json\/wp\/v2\/media?parent=2630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}