{"id":338,"date":"2021-11-14T01:42:25","date_gmt":"2021-11-14T01:42:25","guid":{"rendered":"https:\/\/themenectar.com\/salient\/architect\/?page_id=6"},"modified":"2024-10-02T10:02:38","modified_gmt":"2024-10-02T08:02:38","slug":"about","status":"publish","type":"page","link":"https:\/\/soluwater.com\/sv\/about\/","title":{"rendered":"Om"},"content":{"rendered":"<div id=\"fws_6a57870918895\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"8%\" data-bottom-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  zindex-set right_padding_6pct left_padding_6pct top_padding_tablet_20pct top_padding_phone_25pct\"  style=\"padding-top: calc(100vw * 0.08); padding-bottom: calc(100vw * 0.10);  z-index: 100;\"><div class=\"row-bg-wrap\" data-bg-animation=\"fade-in\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57870919259\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-4\/5 vc_col-md-9 wpb_column column_container vc_column_container col child_column no-extra-padding bottom_margin_tablet_20px inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_7-5vw font_size_tablet_9vw font_size_phone_10vw\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"true\" data-stagger=\"true\" data-custom-font-size=\"true\" style=\"font-size: 7.5vw; line-height: 8.25vw;\"><h1 >About Soluwater<\/h1><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-1\/5 vc_col-md-3 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding el_spacing_10px inherit_tablet inherit_phone mobile-disable-entrance-animation\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"500\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"margin-right: 25px; \"><h6 style=\"color: #0a0a0a;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #0a0a0a;\" role=\"button\" href=\"#team\">Team<\/a><\/span><\/h6><\/div><div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" style=\"margin-right: 25px; \"><h6 style=\"color: #0a0a0a;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #0a0a0a;\" role=\"button\" href=\"#about\">Values<\/a><\/span><\/h6><\/div><div class=\"nectar-cta  alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inline-block\" data-color=\"default\" data-using-bg=\"false\" data-display=\"block\" data-style=\"underline\" data-alignment=\"left\" data-text-color=\"custom\" ><h6 style=\"color: #0a0a0a;\"> <span class=\"link_wrap\" ><a  class=\"link_text\" style=\"border-color: #0a0a0a;\" role=\"button\" href=\"#values\">Culture<\/a><\/span><\/h6><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a5787091a360\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  top_margin_-5pct right_padding_6pct left_padding_6pct\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone mobile-disable-entrance-animation\" data-using-bg=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"600\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"very_subtle\" data-bg-pos=\"center bottom\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Sede-Soluwater.webp'); \"><\/div><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_tablet_70vh height_phone_50vh\" data-alignment=\"default\"><div style=\"height: 100vh;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a5787091b35e\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"10%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_27pct left_padding_27pct top_padding_tablet_20pct bottom_padding_tablet_10pct right_padding_tablet_20pct right_padding_phone_6pct left_padding_tablet_20pct left_padding_phone_6pct\"  style=\"padding-top: calc(100vw * 0.10); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col centered-text no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a5787091b8b5\" data-midnight=\"\" data-column-margin=\"20px\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"margin-bottom: 20px; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding el_spacing_0px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" data-animation-offset=\"80%\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h5>SOLUWATER<\/h5>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"nectar-split-heading  font_size_4vw font_size_phone_10vw\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"true\" style=\"font-size: 4vw; line-height: 4.4vw;\"><h1 >Creaci\u00f3n y alquiler de plantas m\u00f3viles de tratamiento de agua industriales<\/h1><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"team\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_6pct left_padding_6pct top_padding_tablet_10pct bottom_padding_tablet_10pct\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col nectar-sticky-column-css has-animation no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"n-sticky\"><div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_3vw\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"none\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 3vw; line-height: 3.3vw;\"><h2 >Equipo cualificado<\/h2><\/div><div class=\"nectar-split-heading  font_size_1-1vw font_size_tablet_18px font_size_phone_16px font_line_height_1-7\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"none\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 1.1vw; line-height: 1.21vw;\"><p >Nuestras plantas m\u00f3viles de tratamiento de agua est\u00e1n dise\u00f1adas, desarrolladas y construidas por un equipo de ingenieros, altamente cualificados, que trabajan siempre con una premisa en mente, garantizar la satisfacci\u00f3n y superaci\u00f3n de las expectativas del cliente.<\/p><\/div>\n\t\t\t<\/div> \n\t\t<\/div><\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col padding-6-percent el_spacing_0px no-extra-padding_tablet no-extra-padding_phone\"  data-padding-pos=\"left\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a5787091ccf4\" data-midnight=\"\" data-column-margin=\"30px\" class=\"wpb_row vc_row-fluid vc_row inner_row  top_padding_tablet_40px bottom_padding_tablet_0px\"  style=\"padding-bottom: 20px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"team-member\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" data-style=\"bio_fullscreen_alt\"><div class=\"team-member-image\"><div class=\"team-member-image-inner\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-0.7\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><img loading=\"lazy\" decoding=\"async\" class=\"nectar-lazy\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg%20xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg'%20viewBox%3D'0%200%20500%20500'%2F%3E\" data-nectar-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Carlos-Segura-Roux-500x500.webp\" width=\"500\" height=\"500\" alt=\"Carlos Segura | CEO de Soluwater | Madrid\" \/><\/div><\/div><\/div><\/div><div class=\"team-member-overlay\"><\/div>\n    <div class=\"team-meta\"><h5>CEO, Fundador<\/h5><h3>Carlos Segura Roux<\/h3><p><\/p><\/div>\n    <div class=\"nectar_team_bio_img\" data-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Carlos-Segura-Roux.webp\"><\/div>\n    <div class=\"nectar_team_bio\"><p>Lidera nuestro equipo de profesionales como CEO y fundador. Con una larga trayectoria desde 2004, Carlos se especializa en una amplia gama de tecnolog\u00edas de tratamiento de agua, incluyendo uv, ozono, filtraci\u00f3n underblock y \u00f3smosis inversa.<\/p>\n<p>Su experiencia abarca desde la simple eliminaci\u00f3n de la turbidez hasta la ultra-purificaci\u00f3n del agua.<\/p>\n<p>Carlos es reconocido por dise\u00f1ar, fabricar, instalar y mantener plantas de tratamiento de agua en diversos sectores, desde la industria alimentaria hasta complejos tur\u00edsticos en Asia-Pac\u00edfico.<\/p>\n<div class=\"bottom_meta\"><a href=\"https:\/\/www.linkedin.com\/in\/carlos-segura-roux-88b78817\/\" target=\"_blank\"><i class=\"icon-default-style fa fa-linkedin\"><\/i><\/a><a href=\"mailto:gerencia@soluwater.com\" target=\"_blank\"><i class=\"icon-default-style fa fa-envelope\"><\/i><\/a><\/div><\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"team-member\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" data-style=\"bio_fullscreen_alt\"><div class=\"team-member-image\"><div class=\"team-member-image-inner\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-0.7\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><img loading=\"lazy\" decoding=\"async\" class=\"nectar-lazy\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg%20xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg'%20viewBox%3D'0%200%20500%20500'%2F%3E\" data-nectar-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Departamento-Tecnico-500x500.webp\" width=\"500\" height=\"500\" alt=\"Nuestro departamento t\u00e9cnico altamente cualificado | Soluwater\" \/><\/div><\/div><\/div><\/div><div class=\"team-member-overlay\"><\/div>\n    <div class=\"team-meta\"><h5><\/h5><h3>Departamento T\u00e9cnico<\/h3><p><\/p><\/div>\n    <div class=\"nectar_team_bio_img\" data-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Departamento-Tecnico.webp\"><\/div>\n    <div class=\"nectar_team_bio\"><p>En el departamento t\u00e9cnico-mec\u00e1nico de Soluwater, nuestro equipo est\u00e1 dedicado a garantizar el funcionamiento \u00f3ptimo de todas nuestras soluciones de tratamiento de agua. Con una combinaci\u00f3n \u00fanica de experiencia t\u00e9cnica y habilidades mec\u00e1nicas, somos los encargados de dise\u00f1ar, mantener y mejorar continuamente nuestras plantas m\u00f3viles de tratamiento de agua.<\/p>\n<p>Desde la conceptualizaci\u00f3n hasta la implementaci\u00f3n, trabajamos en estrecha colaboraci\u00f3n con nuestros clientes para asegurarnos de que sus necesidades espec\u00edficas sean atendidas de manera eficiente y efectiva. Nuestro compromiso con la calidad y la innovaci\u00f3n nos impulsa a buscar constantemente nuevas formas de mejorar nuestros productos y servicios, garantizando as\u00ed la satisfacci\u00f3n y el \u00e9xito de nuestros clientes.<\/p>\n<p>En Soluwater, el departamento t\u00e9cnico-mec\u00e1nico es el coraz\u00f3n de nuestra operaci\u00f3n, y estamos aqu\u00ed para asegurarnos de que tu experiencia con nuestras soluciones de tratamiento de agua sea siempre excepcional.<\/p>\n<div class=\"bottom_meta\"><a href=\"#\" target=\"_blank\"><i class=\"icon-default-style fa fa-facebook\"><\/i><\/a><a href=\"#\" target=\"_blank\"><i class=\"icon-default-style fa fa-instagram\"><\/i><\/a><a href=\"#\" target=\"_blank\"><i class=\"icon-default-style fa fa-github\"><\/i><\/a><\/div><\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a5787091f54c\" data-midnight=\"\" data-column-margin=\"30px\" class=\"wpb_row vc_row-fluid vc_row inner_row  vc_custom_1634415872169\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"team-member\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" data-style=\"bio_fullscreen_alt\"><div class=\"team-member-image\"><div class=\"team-member-image-inner\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-0.7\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><img loading=\"lazy\" decoding=\"async\" class=\"nectar-lazy\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg%20xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg'%20viewBox%3D'0%200%20500%20500'%2F%3E\" data-nectar-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Equipo-Soluwater-500x500.webp\" width=\"500\" height=\"500\" alt=\"Nuestro equipo de profesionales del sector del agua | Soluwater | Madrid\" \/><\/div><\/div><\/div><\/div><div class=\"team-member-overlay\"><\/div>\n    <div class=\"team-meta\"><h5><\/h5><h3>Departamento Comercial<\/h3><p><\/p><\/div>\n    <div class=\"nectar_team_bio_img\" data-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Equipo-Soluwater.webp\"><\/div>\n    <div class=\"nectar_team_bio\"><p>Nuestro equipo est\u00e1 formado por profesionales apasionados y comprometidos con ofrecer las mejores soluciones a nuestros clientes. Con una amplia experiencia en el sector del tratamiento de agua, estamos aqu\u00ed para entender tus necesidades y ofrecerte las soluciones m\u00e1s eficientes y sostenibles.<\/p>\n<p>En Soluwater, creemos en la importancia de establecer relaciones s\u00f3lidas y duraderas con nuestros clientes. Estamos aqu\u00ed para ayudarte en cada paso del camino, desde la consulta inicial hasta la implementaci\u00f3n y el soporte continuo.<\/p>\n<p>Conf\u00eda en el equipo comercial de Soluwater para encontrar la soluci\u00f3n perfecta para tus necesidades de tratamiento de agua.<\/p>\n<div class=\"bottom_meta\"><a href=\"mailto:comercial@soluwater.com\" target=\"_blank\"><i class=\"icon-default-style fa fa-envelope\"><\/i><\/a><\/div><\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"    data-t-w-inherits=\"small_desktop\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"team-member\" data-n-parallax-bg=\"true\" data-parallax-speed=\"subtle\" data-style=\"bio_fullscreen_alt\"><div class=\"team-member-image\"><div class=\"team-member-image-inner\"><div class=\"nectar-el-parallax-scroll\" data-scroll-animation=\"true\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-0.7\" data-scroll-animation-lerp=\"1\"><div class=\"vc_column-inner\"><img loading=\"lazy\" decoding=\"async\" class=\"nectar-lazy\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg%20xmlns%3D'http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg'%20viewBox%3D'0%200%20500%20500'%2F%3E\" data-nectar-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Equipo-de-Soldadura-500x500.webp\" width=\"500\" height=\"500\" alt=\"Equipo Cualificado | Soluwater\" \/><\/div><\/div><\/div><\/div><div class=\"team-member-overlay\"><\/div>\n    <div class=\"team-meta\"><h5><\/h5><h3>Departamento de Taller<\/h3><p><\/p><\/div>\n    <div class=\"nectar_team_bio_img\" data-img-src=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Equipo-de-Soldadura.webp\"><\/div>\n    <div class=\"nectar_team_bio\"><p>En el departamento de soldadores de Soluwater, nuestro equipo est\u00e1 formado por profesionales altamente cualificados y dedicados a garantizar la calidad y durabilidad de todas nuestras estructuras y componentes. Con una combinaci\u00f3n de experiencia, habilidad y pasi\u00f3n por la excelencia, somos responsables de fabricar y ensamblar las piezas clave que hacen posible el funcionamiento impecable de nuestras plantas m\u00f3viles de tratamiento de agua.<\/p>\n<p>Desde la soldadura de precisi\u00f3n hasta la inspecci\u00f3n de calidad, trabajamos en estrecha colaboraci\u00f3n con otros departamentos para asegurarnos de que cada componente cumpla con los m\u00e1s altos est\u00e1ndares de rendimiento y seguridad. Nuestra dedicaci\u00f3n a la artesan\u00eda y la atenci\u00f3n al detalle nos distingue, y nos enorgullece contribuir al \u00e9xito de Soluwater y al bienestar de nuestros clientes.<\/p>\n<p>En Soluwater, el departamento de soldadores es un pilar fundamental de nuestra operaci\u00f3n, y estamos comprometidos a mantener los m\u00e1s altos niveles de calidad y profesionalismo en todo lo que hacemos.<\/p>\n<div class=\"bottom_meta\"><a href=\"#\" target=\"_blank\"><i class=\"icon-default-style fa fa-twitter\"><\/i><\/a><a href=\"#\" target=\"_blank\"><i class=\"icon-default-style fa fa-instagram\"><\/i><\/a><\/div><\/div>\n    <\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"about\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_6pct left_padding_6pct top_padding_tablet_10pct bottom_padding_tablet_10pct\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a57870922d92\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"\" class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column no-extra-padding bottom_margin_tablet_40px inherit_tablet inherit_phone\"  data-using-bg=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"very_subtle\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/soluwater.com\/wp-content\/uploads\/2024\/03\/Osmosis-inversa-RO-BW.webp'); \"><\/div><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap height_tablet_75vh\" data-alignment=\"default\"><div style=\"height: 25px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column padding-6-percent no-extra-padding_tablet no-extra-padding_phone\"   data-padding-pos=\"left\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" data-scroll-animation=\"true\" data-scroll-animation-movement=\"default\" data-scroll-animation-mobile=\"\" data-scroll-animation-intensity=\"1\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap height_tablet_0px\" data-alignment=\"default\"><div style=\"height: 30vh;\" class=\"divider\"><\/div><\/div><div class=\"nectar-split-heading  font_size_2-8vw\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"true\" style=\"font-size: 2.8vw; line-height: 3.08vw;\"><h2 >Nuestra propuesta de valor<\/h2><\/div><div class=\"nectar-split-heading  font_size_1-1vw font_size_tablet_18px font_size_phone_16px font_line_height_1-7\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"none\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 1.1vw; line-height: 1.21vw;\"><p >En Soluwater, ofrecemos soluciones de suministro h\u00eddrico confiable y sostenible para la industria mediante el alquiler de nuestras plantas m\u00f3viles de tratamiento de agua, contamos con fabricaci\u00f3n propia y garantizamos tiempos m\u00ednimos de puesta en marcha, brindando una experiencia \u00fanica con garant\u00eda de calidad.<\/p><\/div><div class=\"nectar-cta  border_color_cccccc hover_border_color_565656 border_thickness_1px alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"default\" data-using-bg=\"false\" data-style=\"arrow-animation\" data-display=\"block\" data-alignment=\"left\" data-text-color=\"custom\" style=\"margin-top: 50px; \"><h6 style=\"color: #141414;\"><span class=\"link_wrap\" style=\"padding-top: 15px; padding-right: 40px; padding-bottom: 15px; padding-left: 40px;\"><a  class=\"link_text\" role=\"button\" href=\"#joinchat\"><span class=\"text\">Habla con uno de nuestros expertos<\/span><svg class=\"next-arrow\" aria-hidden=\"true\" width=\"20px\" height=\"25px\" viewbox=\"0 0 50 80\" xml:space=\"preserve\">\n  <polyline stroke=\"#ffffff\" stroke-width=\"9\" fill=\"none\" stroke-linecap=\"round\" stroke-linejoin=\"round\" points=\"0, 0 45, 40 0, 80\"\/>\n  <\/svg>  <span class=\"line\"  style=\"background-color: #141414;\"><\/span> <\/a><\/span><\/h6><\/div><div class=\"divider-wrap height_tablet_0px height_phone_0px\" data-alignment=\"default\"><div style=\"height: 30vh;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"values\"  data-column-margin=\"none\" data-midnight=\"dark\" data-top-percent=\"5%\" data-bottom-percent=\"5%\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-top  right_padding_6pct left_padding_6pct top_padding_tablet_10pct bottom_padding_tablet_20pct\"  style=\"padding-top: calc(100vw * 0.05); padding-bottom: calc(100vw * 0.05); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a578709250f3\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_9vw font_size_tablet_8vw font_size_phone_10vw\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"true\" style=\"font-size: 9vw; line-height: 9.9vw;\"><h1 >Cultura<\/h1><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57870925863\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 22.5px; height: 1px; margin-bottom: 22.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"black\" class=\"divider-border\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57870925de3\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 vc_col-xs-10 wpb_column column_container vc_column_container col child_column has-animation padding-5-percent el_spacing_10px inherit_tablet inherit_phone\"   data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-highlighted-text font_size_2vw\" data-style=\"full_text\" data-exp=\"default\" data-using-custom-color=\"true\" data-animation-delay=\"false\" data-color=\"#3ec4d6\" data-color-gradient=\"#f2f2f2\" style=\"\"><h2><strong><em>Innovaci\u00f3n<\/em><\/strong> continua.<\/h2>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Nos encontramos siempre en la b\u00fasqueda constante de nuevas formas de mejorar y desarrollar soluciones de tratamiento de agua innovadoras para nuestros clientes.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 vc_col-xs-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_7vw font_size_tablet_70px font_size_phone_46px font_line_height_1px\" data-align=\"right\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 7vw; line-height: 7.7vw;\"><h2 >01<\/h2><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57870926ec0\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 22.5px; height: 1px; margin-bottom: 22.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"black\" class=\"divider-border\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57870927394\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 vc_col-xs-10 wpb_column column_container vc_column_container col child_column has-animation padding-5-percent el_spacing_10px inherit_tablet inherit_phone\"   data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-highlighted-text font_size_2vw\" data-style=\"full_text\" data-exp=\"default\" data-using-custom-color=\"true\" data-animation-delay=\"false\" data-color=\"#3ec4d6\" data-color-gradient=\"#f2f2f2\" style=\"\"><h2>Compromiso con la <strong><em>sostenibilidad<\/em><\/strong>.<\/h2>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Nos dedicamos a ofrecer soluciones de tratamiento de agua que sean respetuosas con el medio ambiente y contribuyan a la conservaci\u00f3n de los recursos h\u00eddricos.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 vc_col-xs-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_7vw font_size_tablet_70px font_size_phone_46px font_line_height_1px\" data-align=\"right\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 7vw; line-height: 7.7vw;\"><h2 >02<\/h2><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a57870927d3d\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 22.5px; height: 1px; margin-bottom: 22.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"black\" class=\"divider-border\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a578709281ee\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-middle\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 vc_col-xs-10 wpb_column column_container vc_column_container col child_column has-animation padding-5-percent el_spacing_10px inherit_tablet inherit_phone\"   data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-highlighted-text font_size_2vw\" data-style=\"full_text\" data-exp=\"default\" data-using-custom-color=\"true\" data-animation-delay=\"false\" data-color=\"#3ec4d6\" data-color-gradient=\"#f2f2f2\" style=\"\"><h2>Colaboraci\u00f3n y <strong><em>trabajo en equipo<\/em><\/strong><\/h2>\n<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Valoramos el trabajo en equipo y la colaboraci\u00f3n, creando un ambiente donde cada miembro del equipo puede contribuir al \u00e9xito colectivo de Soluwater.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 vc_col-xs-2 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_7vw font_size_tablet_70px font_size_phone_46px font_line_height_1px\" data-align=\"right\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 7vw; line-height: 7.7vw;\"><h2 >03<\/h2><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"About Soluwater Team Values Culture SOLUWATER Creaci\u00f3n y alquiler de plantas m\u00f3viles de tratamiento de agua industriales Equipo cualificadoNuestras plantas m\u00f3viles de tratamiento de agua est\u00e1n dise\u00f1adas, desarrolladas y construidas...","protected":false},"author":2,"featured_media":862,"parent":0,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-338","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About - Soluwater<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/soluwater.com\/sv\/about\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About - Soluwater\" \/>\n<meta property=\"og:url\" content=\"https:\/\/soluwater.com\/sv\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"Soluwater\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T08:02:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Cabecera-RRSS.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data1\" content=\"29 minuter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/\",\"url\":\"https:\\\/\\\/soluwater.com\\\/about\\\/\",\"name\":\"About - Soluwater\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cabecera-RRSS.webp\",\"datePublished\":\"2021-11-14T01:42:25+00:00\",\"dateModified\":\"2024-10-02T08:02:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/soluwater.com\\\/about\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/#primaryimage\",\"url\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cabecera-RRSS.webp\",\"contentUrl\":\"https:\\\/\\\/soluwater.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Cabecera-RRSS.webp\",\"width\":1200,\"height\":675,\"caption\":\"Alquiler de plantas m\u00f3viles de tratamiento de agua Soluwater\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/soluwater.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/soluwater.com\\\/#website\",\"url\":\"https:\\\/\\\/soluwater.com\\\/\",\"name\":\"Soluwater\",\"description\":\"Alquiler de plantas m\u00f3viles de tratamiento de agua\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/soluwater.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About - Soluwater","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/soluwater.com\/sv\/about\/","og_locale":"sv_SE","og_type":"article","og_title":"About - Soluwater","og_url":"https:\/\/soluwater.com\/sv\/about\/","og_site_name":"Soluwater","article_modified_time":"2024-10-02T08:02:38+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Cabecera-RRSS.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Ber\u00e4knad l\u00e4stid":"29 minuter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/soluwater.com\/about\/","url":"https:\/\/soluwater.com\/about\/","name":"About - Soluwater","isPartOf":{"@id":"https:\/\/soluwater.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/soluwater.com\/about\/#primaryimage"},"image":{"@id":"https:\/\/soluwater.com\/about\/#primaryimage"},"thumbnailUrl":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Cabecera-RRSS.webp","datePublished":"2021-11-14T01:42:25+00:00","dateModified":"2024-10-02T08:02:38+00:00","breadcrumb":{"@id":"https:\/\/soluwater.com\/about\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/soluwater.com\/about\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/soluwater.com\/about\/#primaryimage","url":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Cabecera-RRSS.webp","contentUrl":"https:\/\/soluwater.com\/wp-content\/uploads\/2024\/04\/Cabecera-RRSS.webp","width":1200,"height":675,"caption":"Alquiler de plantas m\u00f3viles de tratamiento de agua Soluwater"},{"@type":"BreadcrumbList","@id":"https:\/\/soluwater.com\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/soluwater.com\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/soluwater.com\/#website","url":"https:\/\/soluwater.com\/","name":"Solvatten","description":"Uthyrning av mobila vattenreningsverk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/soluwater.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"}]}},"_links":{"self":[{"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/pages\/338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/comments?post=338"}],"version-history":[{"count":15,"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/pages\/338\/revisions"}],"predecessor-version":[{"id":551,"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/pages\/338\/revisions\/551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/media\/862"}],"wp:attachment":[{"href":"https:\/\/soluwater.com\/sv\/wp-json\/wp\/v2\/media?parent=338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}